{"id":407,"date":"2014-10-07T14:39:00","date_gmt":"2014-10-07T14:39:00","guid":{"rendered":"https:\/\/www.maxpokerbonus.com\/de\/2014\/10\/07\/ueberblick-die-besten-poker-bonus-angebote-2014\/"},"modified":"2018-12-11T21:14:35","modified_gmt":"2018-12-11T21:14:35","slug":"ueberblick-die-besten-poker-bonus-angebote-2014","status":"publish","type":"post","link":"https:\/\/www.maxpokerbonus.com\/de\/2014\/10\/07\/ueberblick-die-besten-poker-bonus-angebote-2014\/","title":{"rendered":"\u00dcberblick &#8211; die besten Poker Bonus Angebote 2014"},"content":{"rendered":"<p>In den letzten Jahren ist die Anzahl der Online Poker Seiten und Pokerspieler enorm angestiegen. Den aktuellen PokerScout Statistiken zufolge sind im Schnitt mehr als 44.300 Echtgeld Spieler zu jedem Zeitpunkt an den Tischen zu finden und inzwischen tummeln sich rund 600 Pokerseiten im World Wide Web. Der Kampf um die Aufmerksamkeit der Spieler wird dadurch zunehmend harter, gl\u00fccklicherweise kommt aber die starke Konkurrenz den Kunden definitiv zugute, da sie von vielf\u00e4ltigen attraktiven Poker Boni und zus\u00e4tzlichen Tickets Gebrauch machen k\u00f6nnen. Da man bei diesem derma\u00dfen gro\u00dfen \u00dcberangebot schnell den \u00dcberblick verliert, findet hier heraus, was einen guten Poker Bonus ausmacht?<\/p>\n<h2>Wie man einen guten Poker Bonus erkennt?<\/h2>\n<p>Jeder Poker Bonus setzt sich aus 4 unzertrennlichen Komponenten zusammen: Bonush\u00f6he, Abspielbedingungen, Teilauszahlungsbetr\u00e4ge und G\u00fcltigkeitszeitraum. Anders als beim Online Casino Bonus werden die Poker Boni nicht sofort auf euer Pokerkonto \u00fcberwiesen, sondern auf einem separaten Bonuskonto gef\u00fchrt. Besonders wichtig, um die richtige Wahl des Poker Bonus Angebots zu treffen, ist euch von der H\u00f6he des Bonusses nicht blenden zu lassen, sondern nach den Abspielbedingungen Ausschau zu halten. Denn hier entscheidet sich, wie schnell und einfach euer Geld vom Bonuskonto auf euer Spielerkonto gebracht werden kann.<\/p>\n<p>Die Konditionen besagen zudem, ob der Bonus in Schritten oder als Ganzes freigegeben wird. Meistens wird der Bonusbetrag in gleichm\u00e4\u00dfigen Teilbetr\u00e4gen von jeweils $10 ausgezahlt. Bedenkt dabei auch, dass alle Poker Boni zeitlich befristet sind. Das bedeutet, dass euch f\u00fcr das Abspielen des Bonusses nicht beliebig Zeit zur Verf\u00fcgung steht. \u00dcblicherweise gew\u00e4hren euch die Online Pokerseiten 60 bis 90 Tage, um den Willkommensbonus freizuspielen. Es gibt aber auch Anbieter, wie z. B. PokerStars, die jedem Spieler einen extrem langen Bonuszeitraum von 180 Tagen zum Abspielen zur Verf\u00fcgung stellen.<\/p>\n<h2>Bester Poker Bonus f\u00fcr jeden Spielertyp<\/h2>\n<p><img decoding=\"async\" class=\"alignright\" src=\"https:\/\/www.maxpokerbonus.com\/de\/wp-content\/uploads\/de\/315_888_poker_auszeichnungen.jpg\" alt=\"888 Poker Auszeichnungen\"\/>Wer also gerade erst einsteigt und auf der Suche nach einem guten Bonus ist, der kommt an 888 Poker nicht vorbei. Dieser Poker Seite wurde mehrmals mit dem Preis &#8222;Bester Poker Anbieter&#8220; ausgezeichnet und kann inzwischen eine treue Kundschaft von mehr als 10 Millionen Spielern vorweisen. Auch in Hinsicht auf die Boni kann 888 Poker \u00fcberzeugen, da er das mit Abstand beste Poker Bonus Angebot bereith\u00e4lt. Als kleines Dankesch\u00f6n f\u00fcr eure kostenlose Konto-Er\u00f6ffnung belohnt euch dieser seri\u00f6se Poker Seite mit einem $88 gratis Startguthaben, das keinerlei Einzahlung erfordert. Gerade Anf\u00e4nger sind mit diesem gratis Startgeschenk gut beraten. Dar\u00fcber hinaus wird eure Ersteinzahlung mit einem 100% Bonus von bis zu $800 verg\u00fctet, dessen Bonusbedingungen besonders leicht ausfallen. Freigegeben wird dieser in $10 Schritten, wobei euch mit 90 Tagen sehr viel Zeit zum Freispielen bleibt. Zus\u00e4tzlich werdet ihr euch mit der ersten Einlage eine ganze Reihe von kostenlosen Turniertokens holen.<\/p>\n<p>Gibt es eigentlich gute Alternativen zum 888 Poker? Mit den Bonusangeboten von Titan Poker und PokerStars stehen euch zwei empfehlenswerte Alternativen zur Verf\u00fcgung. Titan Poker eignet sich sehr gut f\u00fcr Freizeitspieler, da er alle Neukunden die Chance gibt, 90 Tage lang gratis an $25 Freeroll Turnieren teilzunehmen. Dank einem sehr langen Zeitraum von 180 Tagen und leichten Konditionen konnte sich auch der $600 PokerStars Bonus unter den besten der Branche einreihen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In den letzten Jahren ist die Anzahl der Online Poker Seiten und Pokerspieler enorm angestiegen. Den aktuellen PokerScout Statistiken zufolge sind im Schnitt mehr als 44.300 Echtgeld Spieler zu jedem Zeitpunkt an den Tischen zu finden und inzwischen tummeln sich rund 600 Pokerseiten im World Wide Web. Der Kampf um die Aufmerksamkeit der Spieler wird [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-407","post","type-post","status-publish","format-standard","hentry","category-poker-promotionen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00dcberblick - die besten Poker Bonus Angebote 2014 | Max Poker Bonus Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.maxpokerbonus.com\/de\/2014\/10\/07\/ueberblick-die-besten-poker-bonus-angebote-2014\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00dcberblick - die besten Poker Bonus Angebote 2014 | Max Poker Bonus Deutschland\" \/>\n<meta property=\"og:description\" content=\"In den letzten Jahren ist die Anzahl der Online Poker Seiten und Pokerspieler enorm angestiegen. Den aktuellen PokerScout Statistiken zufolge sind im Schnitt mehr als 44.300 Echtgeld Spieler zu jedem Zeitpunkt an den Tischen zu finden und inzwischen tummeln sich rund 600 Pokerseiten im World Wide Web. Der Kampf um die Aufmerksamkeit der Spieler wird [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.maxpokerbonus.com\/de\/2014\/10\/07\/ueberblick-die-besten-poker-bonus-angebote-2014\/\" \/>\n<meta property=\"og:site_name\" content=\"Max Poker Bonus Deutschland\" \/>\n<meta property=\"article:published_time\" content=\"2014-10-07T14:39:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-11T21:14:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.maxpokerbonus.com\/de\/wp-content\/uploads\/de\/315_888_poker_auszeichnungen.jpg\" \/>\n<meta name=\"author\" content=\"jens\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"jens\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.maxpokerbonus.com\\\/de\\\/2014\\\/10\\\/07\\\/ueberblick-die-besten-poker-bonus-angebote-2014\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.maxpokerbonus.com\\\/de\\\/2014\\\/10\\\/07\\\/ueberblick-die-besten-poker-bonus-angebote-2014\\\/\"},\"author\":{\"name\":\"jens\",\"@id\":\"https:\\\/\\\/www.maxpokerbonus.com\\\/de\\\/#\\\/schema\\\/person\\\/772ea221b043cb84fe640baadaa27699\"},\"headline\":\"\u00dcberblick &#8211; die besten Poker Bonus Angebote 2014\",\"datePublished\":\"2014-10-07T14:39:00+00:00\",\"dateModified\":\"2018-12-11T21:14:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.maxpokerbonus.com\\\/de\\\/2014\\\/10\\\/07\\\/ueberblick-die-besten-poker-bonus-angebote-2014\\\/\"},\"wordCount\":522,\"image\":{\"@id\":\"https:\\\/\\\/www.maxpokerbonus.com\\\/de\\\/2014\\\/10\\\/07\\\/ueberblick-die-besten-poker-bonus-angebote-2014\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.maxpokerbonus.com\\\/de\\\/wp-content\\\/uploads\\\/de\\\/315_888_poker_auszeichnungen.jpg\",\"articleSection\":[\"Poker Promotionen\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.maxpokerbonus.com\\\/de\\\/2014\\\/10\\\/07\\\/ueberblick-die-besten-poker-bonus-angebote-2014\\\/\",\"url\":\"https:\\\/\\\/www.maxpokerbonus.com\\\/de\\\/2014\\\/10\\\/07\\\/ueberblick-die-besten-poker-bonus-angebote-2014\\\/\",\"name\":\"\u00dcberblick - die besten Poker Bonus Angebote 2014 | Max Poker Bonus Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.maxpokerbonus.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.maxpokerbonus.com\\\/de\\\/2014\\\/10\\\/07\\\/ueberblick-die-besten-poker-bonus-angebote-2014\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.maxpokerbonus.com\\\/de\\\/2014\\\/10\\\/07\\\/ueberblick-die-besten-poker-bonus-angebote-2014\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.maxpokerbonus.com\\\/de\\\/wp-content\\\/uploads\\\/de\\\/315_888_poker_auszeichnungen.jpg\",\"datePublished\":\"2014-10-07T14:39:00+00:00\",\"dateModified\":\"2018-12-11T21:14:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.maxpokerbonus.com\\\/de\\\/#\\\/schema\\\/person\\\/772ea221b043cb84fe640baadaa27699\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.maxpokerbonus.com\\\/de\\\/2014\\\/10\\\/07\\\/ueberblick-die-besten-poker-bonus-angebote-2014\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.maxpokerbonus.com\\\/de\\\/2014\\\/10\\\/07\\\/ueberblick-die-besten-poker-bonus-angebote-2014\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.maxpokerbonus.com\\\/de\\\/2014\\\/10\\\/07\\\/ueberblick-die-besten-poker-bonus-angebote-2014\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.maxpokerbonus.com\\\/de\\\/wp-content\\\/uploads\\\/de\\\/315_888_poker_auszeichnungen.jpg\",\"contentUrl\":\"https:\\\/\\\/www.maxpokerbonus.com\\\/de\\\/wp-content\\\/uploads\\\/de\\\/315_888_poker_auszeichnungen.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.maxpokerbonus.com\\\/de\\\/2014\\\/10\\\/07\\\/ueberblick-die-besten-poker-bonus-angebote-2014\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.maxpokerbonus.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00dcberblick &#8211; die besten Poker Bonus Angebote 2014\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.maxpokerbonus.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.maxpokerbonus.com\\\/de\\\/\",\"name\":\"Max Poker Bonus Deutschland\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.maxpokerbonus.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.maxpokerbonus.com\\\/de\\\/#\\\/schema\\\/person\\\/772ea221b043cb84fe640baadaa27699\",\"name\":\"jens\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/66d32786b01c13cf5f7618014ea018028f8404d32a9db9136cb50ff958a85844?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/66d32786b01c13cf5f7618014ea018028f8404d32a9db9136cb50ff958a85844?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/66d32786b01c13cf5f7618014ea018028f8404d32a9db9136cb50ff958a85844?s=96&d=mm&r=g\",\"caption\":\"jens\"},\"url\":\"https:\\\/\\\/www.maxpokerbonus.com\\\/de\\\/author\\\/jens\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00dcberblick - die besten Poker Bonus Angebote 2014 | Max Poker Bonus Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.maxpokerbonus.com\/de\/2014\/10\/07\/ueberblick-die-besten-poker-bonus-angebote-2014\/","og_locale":"de_DE","og_type":"article","og_title":"\u00dcberblick - die besten Poker Bonus Angebote 2014 | Max Poker Bonus Deutschland","og_description":"In den letzten Jahren ist die Anzahl der Online Poker Seiten und Pokerspieler enorm angestiegen. Den aktuellen PokerScout Statistiken zufolge sind im Schnitt mehr als 44.300 Echtgeld Spieler zu jedem Zeitpunkt an den Tischen zu finden und inzwischen tummeln sich rund 600 Pokerseiten im World Wide Web. Der Kampf um die Aufmerksamkeit der Spieler wird [&hellip;]","og_url":"https:\/\/www.maxpokerbonus.com\/de\/2014\/10\/07\/ueberblick-die-besten-poker-bonus-angebote-2014\/","og_site_name":"Max Poker Bonus Deutschland","article_published_time":"2014-10-07T14:39:00+00:00","article_modified_time":"2018-12-11T21:14:35+00:00","og_image":[{"url":"https:\/\/www.maxpokerbonus.com\/de\/wp-content\/uploads\/de\/315_888_poker_auszeichnungen.jpg","type":"","width":"","height":""}],"author":"jens","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"jens","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.maxpokerbonus.com\/de\/2014\/10\/07\/ueberblick-die-besten-poker-bonus-angebote-2014\/#article","isPartOf":{"@id":"https:\/\/www.maxpokerbonus.com\/de\/2014\/10\/07\/ueberblick-die-besten-poker-bonus-angebote-2014\/"},"author":{"name":"jens","@id":"https:\/\/www.maxpokerbonus.com\/de\/#\/schema\/person\/772ea221b043cb84fe640baadaa27699"},"headline":"\u00dcberblick &#8211; die besten Poker Bonus Angebote 2014","datePublished":"2014-10-07T14:39:00+00:00","dateModified":"2018-12-11T21:14:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.maxpokerbonus.com\/de\/2014\/10\/07\/ueberblick-die-besten-poker-bonus-angebote-2014\/"},"wordCount":522,"image":{"@id":"https:\/\/www.maxpokerbonus.com\/de\/2014\/10\/07\/ueberblick-die-besten-poker-bonus-angebote-2014\/#primaryimage"},"thumbnailUrl":"https:\/\/www.maxpokerbonus.com\/de\/wp-content\/uploads\/de\/315_888_poker_auszeichnungen.jpg","articleSection":["Poker Promotionen"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.maxpokerbonus.com\/de\/2014\/10\/07\/ueberblick-die-besten-poker-bonus-angebote-2014\/","url":"https:\/\/www.maxpokerbonus.com\/de\/2014\/10\/07\/ueberblick-die-besten-poker-bonus-angebote-2014\/","name":"\u00dcberblick - die besten Poker Bonus Angebote 2014 | Max Poker Bonus Deutschland","isPartOf":{"@id":"https:\/\/www.maxpokerbonus.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.maxpokerbonus.com\/de\/2014\/10\/07\/ueberblick-die-besten-poker-bonus-angebote-2014\/#primaryimage"},"image":{"@id":"https:\/\/www.maxpokerbonus.com\/de\/2014\/10\/07\/ueberblick-die-besten-poker-bonus-angebote-2014\/#primaryimage"},"thumbnailUrl":"https:\/\/www.maxpokerbonus.com\/de\/wp-content\/uploads\/de\/315_888_poker_auszeichnungen.jpg","datePublished":"2014-10-07T14:39:00+00:00","dateModified":"2018-12-11T21:14:35+00:00","author":{"@id":"https:\/\/www.maxpokerbonus.com\/de\/#\/schema\/person\/772ea221b043cb84fe640baadaa27699"},"breadcrumb":{"@id":"https:\/\/www.maxpokerbonus.com\/de\/2014\/10\/07\/ueberblick-die-besten-poker-bonus-angebote-2014\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.maxpokerbonus.com\/de\/2014\/10\/07\/ueberblick-die-besten-poker-bonus-angebote-2014\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.maxpokerbonus.com\/de\/2014\/10\/07\/ueberblick-die-besten-poker-bonus-angebote-2014\/#primaryimage","url":"https:\/\/www.maxpokerbonus.com\/de\/wp-content\/uploads\/de\/315_888_poker_auszeichnungen.jpg","contentUrl":"https:\/\/www.maxpokerbonus.com\/de\/wp-content\/uploads\/de\/315_888_poker_auszeichnungen.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.maxpokerbonus.com\/de\/2014\/10\/07\/ueberblick-die-besten-poker-bonus-angebote-2014\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.maxpokerbonus.com\/de\/"},{"@type":"ListItem","position":2,"name":"\u00dcberblick &#8211; die besten Poker Bonus Angebote 2014"}]},{"@type":"WebSite","@id":"https:\/\/www.maxpokerbonus.com\/de\/#website","url":"https:\/\/www.maxpokerbonus.com\/de\/","name":"Max Poker Bonus Deutschland","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.maxpokerbonus.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.maxpokerbonus.com\/de\/#\/schema\/person\/772ea221b043cb84fe640baadaa27699","name":"jens","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/66d32786b01c13cf5f7618014ea018028f8404d32a9db9136cb50ff958a85844?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/66d32786b01c13cf5f7618014ea018028f8404d32a9db9136cb50ff958a85844?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/66d32786b01c13cf5f7618014ea018028f8404d32a9db9136cb50ff958a85844?s=96&d=mm&r=g","caption":"jens"},"url":"https:\/\/www.maxpokerbonus.com\/de\/author\/jens\/"}]}},"_links":{"self":[{"href":"https:\/\/www.maxpokerbonus.com\/de\/wp-json\/wp\/v2\/posts\/407","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.maxpokerbonus.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.maxpokerbonus.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.maxpokerbonus.com\/de\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.maxpokerbonus.com\/de\/wp-json\/wp\/v2\/comments?post=407"}],"version-history":[{"count":0,"href":"https:\/\/www.maxpokerbonus.com\/de\/wp-json\/wp\/v2\/posts\/407\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.maxpokerbonus.com\/de\/wp-json\/wp\/v2\/media?parent=407"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.maxpokerbonus.com\/de\/wp-json\/wp\/v2\/categories?post=407"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.maxpokerbonus.com\/de\/wp-json\/wp\/v2\/tags?post=407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}